{"id":43059,"date":"2026-05-13T15:00:34","date_gmt":"2026-05-13T20:00:34","guid":{"rendered":"https:\/\/bosquedetlalpan.mx\/?p=43059"},"modified":"2026-05-13T15:24:19","modified_gmt":"2026-05-13T15:24:19","slug":"fiscalia-de-cdmx-descarta-entrevista-laboral-en-feminicidio-de-edith-guadalupe","status":"publish","type":"post","link":"https:\/\/bosquedetlalpan.mx\/index.php\/2026\/05\/13\/fiscalia-de-cdmx-descarta-entrevista-laboral-en-feminicidio-de-edith-guadalupe\/","title":{"rendered":"Fiscal\u00eda de CDMX descarta entrevista laboral en feminicidio de Edith Guadalupe"},"content":{"rendered":"<p>\ud83d\udd38 La fiscal Bertha Alcalde inform\u00f3 que la joven acord\u00f3 reunirse con el presunto agresor por motivos personales; Jes\u00fas \u201cN\u201d permanece en prisi\u00f3n preventiva.<\/p>\n<p>#CDMX | La Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico revel\u00f3 nuevos detalles sobre el feminicidio de Edith Guadalupe y descart\u00f3 que la joven hubiera acudido a una supuesta entrevista de trabajo antes de ser asesinada en un inmueble de la alcald\u00eda Benito Ju\u00e1rez.<\/p>\n<p>Durante el Informe de Seguridad de la capital, la titular de la dependencia, Bertha Alcalde Luj\u00e1n, explic\u00f3 que las investigaciones apuntan a que Edith Guadalupe tuvo contacto previo con el principal sospechoso, identificado como Jes\u00fas \u201cN\u201d.<\/p>\n<p>\u201cSabemos que hubo un contacto previo\u2026 que se quedaron de ver en el edificio por motivos personales, que no est\u00e1 relacionado con un esquema de trata como se manej\u00f3 en medios\u201d, declar\u00f3 la funcionaria.<\/p>\n<p>La fiscal indic\u00f3 que las nuevas pruebas integradas a la carpeta de investigaci\u00f3n incluyen registros de tel\u00e9fono y c\u00e1maras de videovigilancia, elementos que fortalecen las acusaciones contra Jes\u00fas \u201cN\u201d.<\/p>\n<p>Asimismo, Bertha Alcalde se\u00f1al\u00f3 que la familia de Edith Guadalupe solicit\u00f3 discreci\u00f3n en torno al caso para evitar la revictimizaci\u00f3n de la joven.<\/p>\n<p>Por su parte, la jefa de Gobierno de la Ciudad de M\u00e9xico, Clara Brugada Molina, reconoci\u00f3 el trabajo de la Fiscal\u00eda capitalina por la detenci\u00f3n de Jes\u00fas \u201cN\u201d, realizada un d\u00eda despu\u00e9s del hallazgo del cuerpo de Edith Guadalupe en un edificio de la Benito Ju\u00e1rez.<\/p>\n<p>El presunto feminicida permanece bajo prisi\u00f3n preventiva mientras contin\u00faan las investigaciones y se define su situaci\u00f3n jur\u00eddica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 La fiscal Bertha Alcalde inform\u00f3 que la joven acord\u00f3 reunirse con el presunto agresor por motivos personales; Jes\u00fas \u201cN\u201d permanece en prisi\u00f3n preventiva. #CDMX | La Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico revel\u00f3 nuevos detalles sobre el feminicidio de Edith Guadalupe y descart\u00f3 que la joven hubiera acudido a una supuesta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43061,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,3],"tags":[],"class_list":["post-43059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cdmx","category-nacional"],"_links":{"self":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/43059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43059"}],"version-history":[{"count":1,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/43059\/revisions"}],"predecessor-version":[{"id":43060,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/43059\/revisions\/43060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/media\/43061"}],"wp:attachment":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}