{"id":43046,"date":"2026-05-13T11:00:07","date_gmt":"2026-05-13T16:00:07","guid":{"rendered":"https:\/\/bosquedetlalpan.mx\/?p=43046"},"modified":"2026-05-13T15:06:18","modified_gmt":"2026-05-13T15:06:18","slug":"detienen-a-exempleada-de-bbva-por-presunto-fraude-millonario-a-adultos-mayores","status":"publish","type":"post","link":"https:\/\/bosquedetlalpan.mx\/index.php\/2026\/05\/13\/detienen-a-exempleada-de-bbva-por-presunto-fraude-millonario-a-adultos-mayores\/","title":{"rendered":"Detienen a exempleada de BBVA por presunto fraude millonario a adultos mayores"},"content":{"rendered":"<p>\ud83d\udd38 Autoridades de Santiago capturaron a una mujer acusada de despojar de millones de pesos a personas de la tercera edad mientras laboraba en un banco<\/p>\n<p>#NACIONAL | Una mujer que presuntamente aprovech\u00f3 su posici\u00f3n dentro de una instituci\u00f3n bancaria para cometer fraudes millonarios contra personas adultas mayores fue detenida en el municipio de Santiago, Nuevo Le\u00f3n.<\/p>\n<p>De acuerdo con los primeros reportes, la se\u00f1alada, identificada como Griselda \u201cN\u201d, labor\u00f3 en BBVA M\u00e9xico y es investigada por presuntamente desviar recursos de clientes a trav\u00e9s de movimientos relacionados con fondos de inversi\u00f3n, afectando principalmente a personas de la tercera edad.<\/p>\n<p>Su captura fue realizada por elementos de la Polic\u00eda de Santiago, luego de que se integraran denuncias en su contra por presuntas irregularidades financieras.<\/p>\n<p>Seg\u00fan la informaci\u00f3n dada a conocer, la ex empleada bancaria presuntamente se habr\u00eda apoderado de recursos de clientes adultos mayores, aprovechando la confianza que estos depositaban en ella para la administraci\u00f3n de sus ahorros.<\/p>\n<p>Las investigaciones apuntan a que una de las modalidades utilizadas consist\u00eda en movimientos relacionados con fondos de inversi\u00f3n, mediante los cuales los afectados presuntamente perd\u00edan acceso a su dinero sin darse cuenta de inmediato.<\/p>\n<p>Uno de los casos que deton\u00f3 la investigaci\u00f3n fue el de un habitante del municipio de Allende, quien denunci\u00f3 haber sido despojado de aproximadamente 12 millones de pesos que manten\u00eda en una cuenta de ahorro.<\/p>\n<p>Fue al revisar sus estados financieros cuando descubri\u00f3 que los recursos ya no se encontraban disponibles.<\/p>\n<p>Tras la detenci\u00f3n, autoridades estatales hicieron un llamado a la ciudadan\u00eda para que cualquier persona que considere haber sido afectada por este caso acuda a presentar su denuncia ante la Fiscal\u00eda General de Justicia de Nuevo Le\u00f3n.<\/p>\n<p>No se descarta que puedan surgir m\u00e1s denuncias en los pr\u00f3ximos d\u00edas, debido a que la investigaci\u00f3n contin\u00faa abierta para determinar el n\u00famero total de v\u00edctimas y el monto global del presunto fraude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38 Autoridades de Santiago capturaron a una mujer acusada de despojar de millones de pesos a personas de la tercera edad mientras laboraba en un banco #NACIONAL | Una mujer que presuntamente aprovech\u00f3 su posici\u00f3n dentro de una instituci\u00f3n bancaria para cometer fraudes millonarios contra personas adultas mayores fue detenida en el municipio de Santiago, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43048,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,34],"tags":[],"class_list":["post-43046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-nuevo-leon"],"_links":{"self":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/43046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43046"}],"version-history":[{"count":1,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/43046\/revisions"}],"predecessor-version":[{"id":43047,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/43046\/revisions\/43047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/media\/43048"}],"wp:attachment":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}