{"id":42998,"date":"2026-05-12T07:00:23","date_gmt":"2026-05-12T12:00:23","guid":{"rendered":"https:\/\/bosquedetlalpan.mx\/?p=42998"},"modified":"2026-05-12T13:59:48","modified_gmt":"2026-05-12T13:59:48","slug":"el-frente-frio-50-se-extendera-sobre-el-norte-y-occidente-del-golfo-de-mexico","status":"publish","type":"post","link":"https:\/\/bosquedetlalpan.mx\/index.php\/2026\/05\/12\/el-frente-frio-50-se-extendera-sobre-el-norte-y-occidente-del-golfo-de-mexico\/","title":{"rendered":"El frente fr\u00edo 50 se extender\u00e1 sobre el norte y occidente del golfo de M\u00e9xico"},"content":{"rendered":"<p>\ud83d\udd38La\u00a0masa de aire fr\u00edo\u00a0asociada al frente originar\u00e1 refrescamiento de temperaturas en el norte, noreste, oriente y centro de la Rep\u00fablica Mexicana.<\/p>\n<p>#NACIONAL\ud83c\uddf2\ud83c\uddfd II Buenos d\u00edas \u2600\ufe0fll El Servicio Meteorol\u00f3gico Nacional informa que para hoy, el\u00a0frente fr\u00edo n\u00famero 50\u00a0se extender\u00e1 sobre el norte y occidente del golfo de M\u00e9xico hasta el oriente del pa\u00eds, en interacci\u00f3n con un\u00a0canal de baja presi\u00f3n\u00a0sobre el sureste de M\u00e9xico, generar\u00e1n lluvias puntuales fuertes en Veracruz, Tabasco, Oaxaca y Chiapas; e intervalos de chubascos en Nuevo Le\u00f3n y Tamaulipas.<\/p>\n<p>Por su parte, la\u00a0masa de aire fr\u00edo\u00a0asociada al frente originar\u00e1 refrescamiento de temperaturas en el norte, noreste, oriente y centro de la Rep\u00fablica Mexicana.<\/p>\n<p>En contraste, continuar\u00e1 la\u00a0onda de calor\u00a0en Baja California Sur (oeste y sur), Sonora (sur), Sinaloa (norte, centro y sur), Chihuahua (suroeste), Durango (oeste), Nayarit (norte y sur), Jalisco (oeste, sur y suroeste), Colima (este), Michoac\u00e1n (centro y suroeste), Puebla (suroeste), Morelos (suroeste), Guerrero, Oaxaca (sur y este) y Chiapas (centro y suroeste), finalizando a partir de hoy en Veracruz, Tabasco, Campeche y Yucat\u00e1n. A su vez, la entrada de\u00a0aire h\u00famedo\u00a0del mar Caribe ocasionar\u00e1 chubascos en Quintana Roo, Yucat\u00e1n y Campeche.<\/p>\n<p>El ingreso de\u00a0aire h\u00famedo\u00a0del oc\u00e9ano Pac\u00edfico, en combinaci\u00f3n con la corriente en\u00a0chorro subtropical\u00a0y con un\u00a0canal de baja\u00a0presi\u00f3n sobre el occidente del territorio nacional, propiciar\u00e1n lluvias puntuales fuertes en Guerrero, Puebla, Hidalgo, Estado de M\u00e9xico, Michoac\u00e1n, Jalisco y Guanajuato; intervalos de chubascos en Chihuahua, Coahuila, Durango, Zacatecas, Aguascalientes, San Luis Potos\u00ed, Colima, Nayarit, Quer\u00e9taro, Tlaxcala, Morelos y Ciudad de M\u00e9xico; y lluvias aisladas en zonas de Sinaloa y Sonora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd38La\u00a0masa de aire fr\u00edo\u00a0asociada al frente originar\u00e1 refrescamiento de temperaturas en el norte, noreste, oriente y centro de la Rep\u00fablica Mexicana. #NACIONAL\ud83c\uddf2\ud83c\uddfd II Buenos d\u00edas \u2600\ufe0fll El Servicio Meteorol\u00f3gico Nacional informa que para hoy, el\u00a0frente fr\u00edo n\u00famero 50\u00a0se extender\u00e1 sobre el norte y occidente del golfo de M\u00e9xico hasta el oriente del pa\u00eds, en interacci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43000,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-42998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/42998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/comments?post=42998"}],"version-history":[{"count":1,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/42998\/revisions"}],"predecessor-version":[{"id":42999,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/posts\/42998\/revisions\/42999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/media\/43000"}],"wp:attachment":[{"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/media?parent=42998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/categories?post=42998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bosquedetlalpan.mx\/index.php\/wp-json\/wp\/v2\/tags?post=42998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}